{"id":209,"count":17,"description":"","link":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/tag\/interessenkonflikte\/","name":"Interessenkonflikte","slug":"interessenkonflikte","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interessenkonflikte Archives - Der Arzneimittelbrief<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interessenkonflikte Archives - Der Arzneimittelbrief\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/tag\/interessenkonflikte\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Arzneimittelbrief\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.der-arzneimittelbrief.de\/nachrichten\/wp-content\/uploads\/2012\/06\/logo_amb_neu.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.der-arzneimittelbrief.de\\\/nachrichten\\\/tag\\\/interessenkonflikte\\\/\",\"url\":\"https:\\\/\\\/www.der-arzneimittelbrief.de\\\/nachrichten\\\/tag\\\/interessenkonflikte\\\/\",\"name\":\"Interessenkonflikte Archives - Der Arzneimittelbrief\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.der-arzneimittelbrief.de\\\/nachrichten\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.der-arzneimittelbrief.de\\\/nachrichten\\\/tag\\\/interessenkonflikte\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.der-arzneimittelbrief.de\\\/nachrichten\\\/tag\\\/interessenkonflikte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.der-arzneimittelbrief.de\\\/nachrichten\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interessenkonflikte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.der-arzneimittelbrief.de\\\/nachrichten\\\/#website\",\"url\":\"https:\\\/\\\/www.der-arzneimittelbrief.de\\\/nachrichten\\\/\",\"name\":\"Der Arzneimittelbrief\",\"description\":\"Unabh\u00e4ngige Arzneimittelinformationen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.der-arzneimittelbrief.de\\\/nachrichten\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interessenkonflikte Archives - Der Arzneimittelbrief","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Interessenkonflikte Archives - Der Arzneimittelbrief","og_url":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/tag\/interessenkonflikte\/","og_site_name":"Der Arzneimittelbrief","og_image":[{"url":"http:\/\/www.der-arzneimittelbrief.de\/nachrichten\/wp-content\/uploads\/2012\/06\/logo_amb_neu.jpg","type":"","width":"","height":""}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/tag\/interessenkonflikte\/","url":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/tag\/interessenkonflikte\/","name":"Interessenkonflikte Archives - Der Arzneimittelbrief","isPartOf":{"@id":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/#website"},"breadcrumb":{"@id":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/tag\/interessenkonflikte\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/tag\/interessenkonflikte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/"},{"@type":"ListItem","position":2,"name":"Interessenkonflikte"}]},{"@type":"WebSite","@id":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/#website","url":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/","name":"Der Arzneimittelbrief","description":"Unabh\u00e4ngige Arzneimittelinformationen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/wp-json\/wp\/v2\/tags\/209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.der-arzneimittelbrief.de\/nachrichten\/wp-json\/wp\/v2\/posts?tags=209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}